{"id":79,"count":7,"description":"","link":"https:\/\/numero.com\/en\/category\/art-design\/design-en\/","name":"Design","slug":"design-en","taxonomy":"category","parent":76,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Design - Num\u00e9ro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/numero.com\/en\/category\/art-design\/design-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Design - Num\u00e9ro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/numero.com\/en\/category\/art-design\/design-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Num\u00e9ro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NumeroMagazine\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/numero.com\\\/en\\\/category\\\/art-design\\\/design-en\\\/\",\"url\":\"https:\\\/\\\/numero.com\\\/en\\\/category\\\/art-design\\\/design-en\\\/\",\"name\":\"Design - Num\u00e9ro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/numero.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/numero.com\\\/en\\\/category\\\/art-design\\\/design-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/numero.com\\\/en\\\/category\\\/art-design\\\/design-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/numero.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Art &amp; Design\",\"item\":\"https:\\\/\\\/numero.com\\\/en\\\/category\\\/art-design\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Design\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/numero.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/numero.com\\\/en\\\/\",\"name\":\"Num\u00e9ro\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/numero.com\\\/en\\\/#organization\"},\"alternateName\":\"Num\u00e9ro Magazine\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/numero.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/numero.com\\\/en\\\/#organization\",\"name\":\"Num\u00e9ro\",\"url\":\"https:\\\/\\\/numero.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/numero.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/numero.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo.svg\",\"contentUrl\":\"https:\\\/\\\/numero.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Logo.svg\",\"width\":907,\"height\":181,\"caption\":\"Num\u00e9ro\"},\"image\":{\"@id\":\"https:\\\/\\\/numero.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/numeromagazine\\\/\",\"https:\\\/\\\/x.com\\\/NumeroMagazine\",\"https:\\\/\\\/www.instagram.com\\\/numeromagazine\\\/\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/Num\u00e9ro_(magazine)\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Design - Num\u00e9ro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/numero.com\/en\/category\/art-design\/design-en\/","og_locale":"en_US","og_type":"article","og_title":"Design - Num\u00e9ro","og_url":"https:\/\/numero.com\/en\/category\/art-design\/design-en\/","og_site_name":"Num\u00e9ro","twitter_card":"summary_large_image","twitter_site":"@NumeroMagazine","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/numero.com\/en\/category\/art-design\/design-en\/","url":"https:\/\/numero.com\/en\/category\/art-design\/design-en\/","name":"Design - Num\u00e9ro","isPartOf":{"@id":"https:\/\/numero.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/numero.com\/en\/category\/art-design\/design-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/numero.com\/en\/category\/art-design\/design-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/numero.com\/en\/"},{"@type":"ListItem","position":2,"name":"Art &amp; Design","item":"https:\/\/numero.com\/en\/category\/art-design\/"},{"@type":"ListItem","position":3,"name":"Design"}]},{"@type":"WebSite","@id":"https:\/\/numero.com\/en\/#website","url":"https:\/\/numero.com\/en\/","name":"Num\u00e9ro","description":"","publisher":{"@id":"https:\/\/numero.com\/en\/#organization"},"alternateName":"Num\u00e9ro Magazine","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/numero.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/numero.com\/en\/#organization","name":"Num\u00e9ro","url":"https:\/\/numero.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/numero.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/numero.com\/wp-content\/uploads\/2024\/04\/Logo.svg","contentUrl":"https:\/\/numero.com\/wp-content\/uploads\/2024\/04\/Logo.svg","width":907,"height":181,"caption":"Num\u00e9ro"},"image":{"@id":"https:\/\/numero.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/numeromagazine\/","https:\/\/x.com\/NumeroMagazine","https:\/\/www.instagram.com\/numeromagazine\/","https:\/\/fr.wikipedia.org\/wiki\/Num\u00e9ro_(magazine)"]}]}},"_links":{"self":[{"href":"https:\/\/numero.com\/en\/wp-json\/wp\/v2\/categories\/79","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/numero.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/numero.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/numero.com\/en\/wp-json\/wp\/v2\/categories\/76"}],"wp:post_type":[{"href":"https:\/\/numero.com\/en\/wp-json\/wp\/v2\/posts?categories=79"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}